{"id":1687,"date":"2022-07-18T19:28:22","date_gmt":"2022-07-18T22:28:22","guid":{"rendered":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/?p=1687"},"modified":"2022-07-18T19:28:24","modified_gmt":"2022-07-18T22:28:24","slug":"como-instalar-el-lavadero-de-la-cocina-bacha-de-cocina","status":"publish","type":"post","link":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/como-instalar-el-lavadero-de-la-cocina-bacha-de-cocina\/","title":{"rendered":"\u00bfC\u00f3mo instalar el lavadero de la cocina? (Bacha de cocina)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Como-instalar-el-lavadero-de-la-cocina.jpg\" alt=\"\" class=\"wp-image-1689\" srcset=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Como-instalar-el-lavadero-de-la-cocina.jpg 1024w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Como-instalar-el-lavadero-de-la-cocina-300x169.jpg 300w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Como-instalar-el-lavadero-de-la-cocina-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Cuando se tiene la oportunidad de planificar la construcci\u00f3n de la cocina, hay que tener en cuenta no s\u00f3lo su decoraci\u00f3n, sino los materiales que se utilizar\u00e1n para los distintos espacios que son necesarios para cocinar y lavar los utensilios y platos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"206\" src=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Bachas-o-lavaderos-de-cocina-disponibles-en-el-catalogo-de-Sanitarios-Plasticos1-1024x206.jpg\" alt=\"\" class=\"wp-image-1688\" srcset=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Bachas-o-lavaderos-de-cocina-disponibles-en-el-catalogo-de-Sanitarios-Plasticos1-1024x206.jpg 1024w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Bachas-o-lavaderos-de-cocina-disponibles-en-el-catalogo-de-Sanitarios-Plasticos1-300x60.jpg 300w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Bachas-o-lavaderos-de-cocina-disponibles-en-el-catalogo-de-Sanitarios-Plasticos1-768x154.jpg 768w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/07\/Bachas-o-lavaderos-de-cocina-disponibles-en-el-catalogo-de-Sanitarios-Plasticos1.jpg 1081w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><a href=\"https:\/\/www.sanitariosplasticos.com.ar\/domicilio\/cocina\/bachas\/acero-inoxidable\" target=\"_blank\" rel=\"noreferrer noopener\">Hace clic para ver m\u00e1s bachas para la cocina<\/a><\/figcaption><\/figure>\n\n\n\n<p>El m\u00e1s importante de los lugares es el<a href=\"https:\/\/www.sanitariosplasticos.com.ar\/domicilio\/cocina\/bachas\/acero-inoxidable\" target=\"_blank\" rel=\"noreferrer noopener\"> lavadero de la cocina<\/a> y su instalaci\u00f3n no es f\u00e1cil, raz\u00f3n por la cual debe ser realizada por un especialista con experiencia en el rubro, aunque, podemos tratar de hacerlo por nuestros propios medios. Para que con el tiempo no tengamos los cl\u00e1sicos problemas de resumideros y fregaderos de cocina como cuando se tapan las ca\u00f1er\u00edas conviene seguir los pasos al pie de la letra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A continuaci\u00f3n, listamos algunos consejos pr\u00e1cticos para la instalaci\u00f3n de fregaderos y lavaderos de cocina:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Tener los elementos y las herramientas adecuadas para la realizaci\u00f3n del trabajo. Por ejemplo, contar con todas las partes del fregadero, incluyendo el grifo, el filtro, trampa de grasa y la tuber\u00eda. Un taladro el\u00e9ctrico, una sierra, cinta m\u00e9trica y herramientas para la plomer\u00eda. Adem\u00e1s, contar con cinta adhesiva y la masilla de plomero.<\/li><li>Medir debajo de la encimera para conocer el espacio para el fregadero. Esto posibilita que se adquiera el fregadero de tama\u00f1o correcto, para evitar futuros problemas.<\/li><li>Colocar el fregadero en la posici\u00f3n que ir\u00e1 y marcar sus bordes para realizar los cortes necesarios para su instalaci\u00f3n. Recuerde dejar dos cent\u00edmetros hasta el nivel de la mesada.<\/li><li>Instalar los grifos correspondientes siguiendo las instrucciones que los mismos traen en su envoltorio o consultar a un especialista.<\/li><li>Ubique el lavadero en su posici\u00f3n y aplique la masilla de plomero para que no haya p\u00e9rdidas de l\u00edquidos por otro lugar que no sea el resumidero.<\/li><li>Por \u00faltimo, conecte los grifos, los ca\u00f1os para el sif\u00f3n del lavadero y las ca\u00f1er\u00edas que desembocan en el drenaje.<\/li><\/ul>\n\n\n\n<p>Con estos simples pasos, es posible&nbsp;<strong>instalar el lavadero de la cocina<\/strong>. Sin embargo, si existe alguna duda importante sobre ellos, lo mejor es llamar a un profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se tiene la oportunidad de planificar la construcci\u00f3n de la cocina, hay que tener en cuenta no s\u00f3lo su decoraci\u00f3n, sino los materiales que se utilizar\u00e1n para los distintos &hellip; <\/p>\n","protected":false},"author":5,"featured_media":1690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-1687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar"],"_links":{"self":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1687"}],"version-history":[{"count":1,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1687\/revisions"}],"predecessor-version":[{"id":1692,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1687\/revisions\/1692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media\/1690"}],"wp:attachment":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}