{"id":1460,"date":"2022-02-26T15:25:12","date_gmt":"2022-02-26T18:25:12","guid":{"rendered":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/?p=1460"},"modified":"2022-02-26T15:28:21","modified_gmt":"2022-02-26T18:28:21","slug":"como-limpiar-correctamente-las-canaletas","status":"publish","type":"post","link":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/como-limpiar-correctamente-las-canaletas\/","title":{"rendered":"\u00bfC\u00f3mo limpiar correctamente las canaletas?"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfC\u00f3mo limpiar y reparar canaletas?\" width=\"735\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/C1GA_4yDNWY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Las hojas y otros desechos que obstruyen las canaletas pueden da\u00f1ar el maderaje de tu casa. Debes limpiar las canaletas al menos una vez al a\u00f1o, a menos que tengas \u00e1rboles colgantes, en cuyo caso necesitar\u00e1s limpiarlas dos veces al a\u00f1o.<sup> \u00a0<\/sup>Si vas a utilizar una escalera, debes asegurarte de que sea estable para luego limpiar las canaletas de manera met\u00f3dica con la mano. Si deseas limpiarlas desde el suelo, debes hacerlo con una aspiradora casera. Puedes utilizar una aspiradora vac\u00eda o seca para pasarla sobre las canaletas y eliminar los desechos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sanitariosplasticos.com.ar\/domicilio\/canaletas\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"537\" src=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/02\/Canaletas-tigre-sanitarios-plasticos-1024x537.png\" alt=\"\" class=\"wp-image-1461\" srcset=\"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/02\/Canaletas-tigre-sanitarios-plasticos-1024x537.png 1024w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/02\/Canaletas-tigre-sanitarios-plasticos-300x157.png 300w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/02\/Canaletas-tigre-sanitarios-plasticos-768x402.png 768w, https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-content\/uploads\/2022\/02\/Canaletas-tigre-sanitarios-plasticos.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption><a href=\"https:\/\/www.sanitariosplasticos.com.ar\/domicilio\/canaletas\" target=\"_blank\" rel=\"noreferrer noopener\">Canaletas disponibles en Sanitarios Pl\u00e1sticos<\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9todo <strong>1<\/strong>: Prepararte para limpiar de manera segura las canaletas con una escalera<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-1.jpg\"><\/a>1<strong>Utiliza ropa de trabajo y guantes de goma.<\/strong>\u00a0La limpieza de las canaletas puede resultar un trabajo sucio. Adem\u00e1s, las canaletas pueden estar bastante afiladas. Por estas razones, debes utilizar ropa de trabajo (que no te importe manchar) y unos guantes de goma resistentes.<ul><li>Incluso en climas c\u00e1lidos, debes utilizar una camisa de manga larga mientras limpias. Esto te proporcionar\u00e1 protecci\u00f3n adicional contra los insectos y los bordes afilados de las canaletas.<\/li><li>Si vas a limpiarlas en un d\u00eda seco (en especial en \u00e1reas polvorientas), debes utilizar una mascarilla protectora para evitar que el polvo y el polen ingresen a tus pulmones.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-2.jpg\"><\/a>2<strong>Coloca la escalera.<\/strong>\u00a0Debes colocar la escalera justo donde planeas comenzar la limpieza. Si es posible, debes apoyarla contra la pared de tu casa. De lo contrario, puedes apoyarla sobre la canaleta que se encuentra unida a la casa utilizando algo que sujete la escalera (por ejemplo, un clavo).<ul><li>Antes de utilizar la escalera, debes probarla para comprobar su estabilidad subiendo un pelda\u00f1o o dos con mucho cuidado. Si la escalera se inclina o se tambalea, debes volver a acomodarla hasta que se quede firme.<\/li><li>Si el terreno es blando, la escalera puede hundirse de manera peligrosa. Debes colocar pedazos de madera del mismo tama\u00f1o debajo de los pies de la escalera para evitar que se hunda. Luego, prueba la escalera una vez m\u00e1s para verificar su estabilidad. Puedes volver a acomodar la escalera seg\u00fan sea necesario.<\/li><li>Un terreno desnivelado o en pendiente puede hacer que la escalera se incline. Debes nivelar la escalera colocando pedazos de madera debajo del lado inclinado. Prueba la escalera y realiza los ajustes necesarios para que logres una mayor estabilidad.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-3.jpg\"><\/a>3<strong>Amarra un balde a la escalera para depositar los escombros.<\/strong>\u00a0Endereza una percha de alambre, pero deja el gancho tal y como est\u00e1. Debes formar una pieza recta de metal que termine con un gancho en el extremo. Dobla el extremo opuesto al gancho alrededor del mango del balde y cu\u00e9lgalo en el segundo pelda\u00f1o desde la parte superior.<ul><li>La mayor\u00eda de los desechos en las canaletas son biodegradables. Si deseas, puedes arrojarlos a la tierra para que se descompongan o\u00a0fabriques composta\u00a0con ellos.<\/li><li>Si te resulta m\u00e1s pr\u00e1ctico, puedes colocar un balde de basura grande, una lona o una carretilla junto a la escalera. Luego, arroja los residuos en estos dep\u00f3sitos.<\/li><li>Si no tienes otra opci\u00f3n, puedes utilizar una bolsa de pl\u00e1stico como sustituto, pero puede resultarte dif\u00edcil y peligroso manejarla, en especial si corre mucho viento.<\/li><\/ul><\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9todo <strong>2<\/strong>: Eliminar los escombros de las canaletas con una escalera<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-4.jpg\"><\/a>1<strong>Elimina los escombros con la mano.<\/strong>\u00a0Debes colocarte un guante para levantar las acumulaciones y la suciedad de tus canaletas. Como alternativa, puedes utilizar una herramienta para limpiar (por ejemplo, una paleta de jardiner\u00eda, una pala de mano o una cuchara de pl\u00e1stico). No debes buscar los escombros, tan solo retira los que se encuentren a tu alcance.<ul><li>Para llevar a cabo una limpieza m\u00e1s segura, debes pedirle a un amigo o familiar que sujete la escalera mientras trabajas para proporcionarte estabilidad adicional.<\/li><li>Si tratas de alcanzar un punto demasiado lejano sobre una escalera, podr\u00edas poner en peligro su estabilidad y hacer que se caiga, lo que podr\u00eda causarte una lesi\u00f3n grave.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-5.jpg\"><\/a>2<strong>Cambia la escalera de posici\u00f3n para que contin\u00faes eliminando los desechos.<\/strong>\u00a0Cuando una secci\u00f3n se encuentre libre de escombros, debes bajar de la escalera y moverla para que puedas alcanzar la siguiente secci\u00f3n de la canaleta. Luego, debes eliminar los escombros como ya se describi\u00f3. Contin\u00faa cambiando de posici\u00f3n y limpiando hasta que las canaletas se encuentren completamente despejadas.<\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-6.jpg\"><\/a>3<strong>Limpia las canaletas con agua.<\/strong>\u00a0Amarra una manguera de jard\u00edn a una vara, una podadora de \u00e1rboles o una rama robusta. Abre la llave del grifo y eleva la manguera hacia la canaleta. De esta manera, enjuagar\u00e1s toda la canaleta para finalizar su limpieza. Debes revisar los bajantes pluviales que presentan un flujo desigual o d\u00e9bil, ya que podr\u00edan estar obstruidos.<ul><li>Si sospechas que existe una obstrucci\u00f3n dentro del bajante, debes colocar la escalera a su costado y golpearlo suavemente con un destornillador de arriba abajo. Por lo general, un ruido sordo es indicio de una obstrucci\u00f3n.<\/li><li>Los bajantes pluviales tambi\u00e9n se pueden desconectar de la casa y la canaleta. Coloca el bajante en el suelo y despeja las obstrucciones utilizando un palo largo, un soplador de hojas o una hidrolavadora.<\/li><\/ul><\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9todo <strong>3: <\/strong>Fabricar una aspiradora de canaletas casera<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-7.jpg\"><\/a>1<strong>Equipa la aspiradora con un accesorio de extensi\u00f3n r\u00edgido.<\/strong>\u00a0Debes utilizar \u00fanicamente aspiradoras que puedan manejar materiales h\u00famedos y secos (por ejemplo, un aspirador de astillas o una industrial para talleres h\u00famedos o secos). Coloca la aspiradora en el lugar en el que planeas comenzar a limpiar las canaletas. Inserta la manguera m\u00e1s larga en la aspiradora y asegura la extensi\u00f3n r\u00edgida m\u00e1s larga a la manguera.<ul><li>Es probable que el cable de alimentaci\u00f3n de la aspiradora no sea lo suficientemente largo como para que llegue a un enchufe. Si este es el caso, debes utilizar un cable de extensi\u00f3n para suministrarle la energ\u00eda a la aspiradora.<\/li><li>Para este proyecto, debes escoger una aspiradora que cuente con un motor resistente. Las aspiradoras con succi\u00f3n d\u00e9bil no resultar\u00e1n tan efectivas.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-8.jpg\"><\/a>2<strong>Calcula la medida de la extensi\u00f3n secundaria.<\/strong>\u00a0Mide la longitud total del accesorio de extensi\u00f3n r\u00edgido. Al medir la altura de la canaleta, debes hacerlo desde la parte superior de esta hasta la altura de la rodilla. Luego, debes restar la longitud del accesorio de la altura de la canaleta. Esta medida debe ser la longitud total de la extensi\u00f3n secundaria.<ul><li>Al utilizar la aspiradora para canaletas, es probable que sujetes el accesorio a aproximadamente la altura del pecho. Si mides la canaleta desde su parte superior hasta el suelo, es probable que obtengas como resultado una aspiradora m\u00e1s larga de lo necesario, por lo que te resultar\u00e1 m\u00e1s dif\u00edcil manejarla.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-9.jpg\"><\/a>3<strong>Corta un tubo de pl\u00e1stico r\u00edgido con una segueta.<\/strong>\u00a0Marca la medida de la extensi\u00f3n secundaria (la altura de la canaleta y la longitud del accesorio) sobre el tubo de pl\u00e1stico r\u00edgido. Utiliza una segueta para cortar el pl\u00e1stico a la longitud de la extensi\u00f3n secundaria. Puedes reutilizar o desechar el tubo que sobre.<ul><li>Es probable que dejes rebabas al cortar el tubo. Estas pueden provocar rayones o cortes, por lo que debes eliminarlas con una escofina cada vez que sea necesario.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-10.jpg\"><\/a>4<strong>Ensambla la aspiradora de canaletas.<\/strong> Desliza el extremo del accesorio de la extensi\u00f3n dentro de la extensi\u00f3n secundaria y une ambas piezas firmemente utilizando cinta de aluminio. Debes llevar a cabo el mismo procedimiento en el extremo opuesto de la extensi\u00f3n secundaria con un codo para ducto. Cuando el primer codo se encuentre en su sitio, debes agregar el segundo de manera similar.<sup><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#_note-14\">[14]<\/a><\/sup><ul><li>Al unir estas piezas, tendr\u00e1s como resultado una extensi\u00f3n larga, recta y r\u00edgida que terminar\u00e1 en un gancho. El gancho formado por los codos debe curvarse, de manera que se encuentre orientado hacia abajo.<\/li><li>Aseg\u00farate de pegar minuciosamente las conexiones de la aspiradora casera. Si existen grietas, estas pueden provocar que la potencia de succi\u00f3n disminuya, haciendo que la aspiradora se vuelva menos efectiva.<\/li><\/ul><\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9todo <strong>4<\/strong>: Utilizar una aspiradora de canaletas casera<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-11.jpg\"><\/a>1<strong>Limpia las canaletas.<\/strong>\u00a0Debes mantener la aspiradora aproximadamente en la base del accesorio de extensi\u00f3n. Enciende la aspiradora y pasa el extremo del gancho lentamente sobre la canaleta para eliminar las hojas, ramitas y otros desechos.<ul><li>Si las canaletas se encuentran especialmente obstruidas, es probable que necesites vaciar la aspiradora a medida que limpias. Las aspiradoras excesivamente llenas pueden experimentar una disminuci\u00f3n en la potencia de succi\u00f3n y dejar acumulaciones en las canaletas.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-12.jpg\"><\/a>2<strong>Inspecciona las canaletas para detectar escombros sueltos.<\/strong>\u00a0Incluso si la mayor parte de las acumulaciones ha desaparecido despu\u00e9s de pasar la aspiradora, es probable que algunas obstrucciones resistentes persistan. Debes apoyar una escalera adecuada contra la casa y subirte para inspeccionar las canaletas. B\u00e1jate de la escalera y luego apunta la aspiradora hacia las obstrucciones restantes.<ul><li>Es probable que algunas obstrucciones a\u00fan permanezcan incluso despu\u00e9s de haberles pasado la aspiradora. Puedes utilizar una podadora de \u00e1rboles o una vara s\u00f3lida para golpear y aflojar estas obstrucciones. Luego, debes aspirar los escombros sueltos.<\/li><\/ul><\/li><li><a href=\"https:\/\/es.wikihow.com\/limpiar-canaletas#\/Imagen:Clean-High-Gutters-Step-13.jpg\"><\/a>3<strong>Elimina los restos peque\u00f1os y controla el flujo del bajante pluvial.<\/strong>\u00a0Amarra una manguera de jard\u00edn a una vara larga. Abre la llave del grifo y eleva la manguera hasta la canaleta. Debes enjuagar toda la canaleta con agua para eliminar los restos peque\u00f1os que quedan. Un flujo de agua deficiente en el bajante pluvial puede indicar una obstrucci\u00f3n en su interior.<ul><li>Las obstrucciones en los bajantes se pueden eliminar utilizando una barrena. Debes utilizar esta herramienta de la misma forma en que lo har\u00edas con un\u00a0desag\u00fce atascado.<\/li><\/ul><\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Advertencias<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Las canaletas son a menudo muy afiladas. Para evitar cortes, debes utilizar siempre una camisa de manga larga y guantes de goma resistentes al limpiarlas.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las hojas y otros desechos que obstruyen las canaletas pueden da\u00f1ar el maderaje de tu casa. Debes limpiar las canaletas al menos una vez al a\u00f1o, a menos que tengas &hellip; <\/p>\n","protected":false},"author":5,"featured_media":1463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-1460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar"],"_links":{"self":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1460"}],"version-history":[{"count":2,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1460\/revisions"}],"predecessor-version":[{"id":1467,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1460\/revisions\/1467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}