{"id":1344,"date":"2021-12-29T11:00:27","date_gmt":"2021-12-29T14:00:27","guid":{"rendered":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/?p=1344"},"modified":"2021-12-29T11:00:29","modified_gmt":"2021-12-29T14:00:29","slug":"como-mantener-y-limpiar-piscinas-12-consejos-utiles","status":"publish","type":"post","link":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/como-mantener-y-limpiar-piscinas-12-consejos-utiles\/","title":{"rendered":"C\u00f3mo mantener y limpiar piscinas (12 Consejos \u00fatiles)"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.sanitariosplasticos.com.ar\/pileta\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/como-limpiar-piscina-669x440.jpg\" alt=\"como limpiar una piscina\"\/><\/a><figcaption><a href=\"https:\/\/www.sanitariosplasticos.com.ar\/pileta\" target=\"_blank\" rel=\"noreferrer noopener\">Ingres\u00e1 para ver todo el cat\u00e1logo de mantenimiento de piscinas<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Consejos para limpiar una piscina y mantenerla todo el a\u00f1o<\/strong><\/h2>\n\n\n\n<p>En el verano, casi todos disfrutamos de nuestros ba\u00f1os y chapuzones en alg\u00fan tipo de estanque, sea artificial o no, pero\u2026 para que la diversi\u00f3n no se transforme en disgusto, es necesario un&nbsp;<strong>mantenimiento de la piscina<\/strong>&nbsp;antes, durante y despu\u00e9s de su uso, sin esperar a ese \u00faltimo momento, ya que el agua es un medio ideal para la reproducci\u00f3n de bacterias, hongos y microorganismos, responsables de enfermedades e infecciones que se pueden agravarse.<\/p>\n\n\n\n<p>En esta gu\u00eda de consulta veremos todo lo necesario para entender\u00a0<strong>c\u00f3mo limpiar una piscina\u00a0<\/strong>, sus productos, higiene, el tema de la depuraci\u00f3n y accesorios para poder disfrutarla adecuadamente repasando los puntos destacados del mantenimiento que debe de tener a lo largo de todo el a\u00f1o, sea verano o invierno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Componentes y partes de una piscina<\/strong><\/h3>\n\n\n\n<p>No podemos practicar una&nbsp;<em>desinfecci\u00f3n e higiene de una piscina o una alberca<\/em>&nbsp;si no conocemos el sistema que la hace funcionar y el volumen, por lo menos, en modo esquem\u00e1tico. As\u00ed que dejamos un peque\u00f1o dibujo que refleja el&nbsp;<em>sistema de&nbsp;<\/em><strong>funcionamiento est\u00e1ndar de las piscinas<\/strong>&nbsp;tradicionales que cualquiera puede tener instalado en su jard\u00edn:<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20969\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/partes-de-una-piscina-669x418.jpg\" alt=\"componentes de una piscina\" class=\"wp-image-20969\"\/><figcaption>Esquema componentes de una piscina y flujo del agua \u2013 V\u00eda Leroy Merlin<\/figcaption><\/figure>\n\n\n\n<p>En la instalaci\u00f3n, el&nbsp;<em>flujo del agua de la pileta<\/em>&nbsp;estar\u00e1 succionada por la bomba, pasar\u00e1 por el filtro (Eliminaci\u00f3n elementos externos como hojas e impurezas), despu\u00e9s por la c\u00e9lula electrol\u00edtica (Este mecanismo no siempre est\u00e1) d\u00f3nde se produce el proceso de electrolisis y finalmente el agua desinfectada vuelve al vaso.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo calcular el volumen de agua en una piscina?<\/strong><\/h4>\n\n\n\n<p>Este aspecto es importante para poder elegir el tratamiento a medida con los productos qu\u00edmicos a aplicar, la bomba necesaria, los filtros y skimmers. En el siguiente esquema podemos testear&nbsp;<strong>c\u00f3mo calcular los litros de una piscina rectangular, las ovaladas o redondas<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20971\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/volumen-piscina-669x315.jpg\" alt=\"c\u00f3mo calcular volumen piscina\" class=\"wp-image-20971\"\/><figcaption>V\u00eda Leroy Merlin<\/figcaption><\/figure>\n\n\n\n<p>Recordemos que el resultado ser\u00e1 en metros c\u00fabicos de agua, es decir\u2026&nbsp;<em>\u00bfCu\u00e1ntos litros caben en el vaso?&nbsp;<\/em>Da igual si es de una&nbsp;<strong>piscina de fibra<\/strong>&nbsp;de vidrio&nbsp;y resina de pili\u00e9ster, de hormig\u00f3n liso con los t\u00edpicos azulejos de colores, el valor ser\u00e1 el mismo para los modelos de:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Volumen de una piscina rectangular<\/strong>. Se calcula multiplicando: Largo x Ancho x Profundidad media<\/li><li><strong>Volumen en una piscina redonda<\/strong>. Se calcula multiplicando: Di\u00e1metro x Di\u00e1metro x Profundidad media x Coeficiente (0.785)<\/li><li><strong>Volumen de una piscina ovalada<\/strong>. Se calcula multiplicando: Largo x Ancho x Profundidad media x Coeficiente (0.89)<\/li><\/ul>\n\n\n\n<p><strong>Total litros de agua<\/strong>&nbsp;= (Nuestro dato Volumen calculado) m3 x 1.000 Litros\/m3 =&nbsp;<strong>Total litros de agua que tiene la piscina<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Y llegados a este punto, toca ver&nbsp;<strong>c\u00f3mo se limpia una piscina<\/strong>&nbsp;y qu\u00e9 tenemos que tener en cuenta\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mantenimiento piscinas<\/strong><\/h3>\n\n\n\n<p>En esta secci\u00f3n aportamos un esquema y te explicamos los pasos que hay que llevar a cabo, tanto si has practicado el \u00ab<strong>invernaje\u00bb<\/strong>&nbsp;(Referido al tratamiento qu\u00edmico para&nbsp;<strong>mantener la piscina durante el invierno<\/strong>), como si no, las tareas ser\u00edan:<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20982\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/mantenimiento-piscina-669x252.jpg\" alt=\"mantenimiento de una piscina\" class=\"wp-image-20982\"\/><figcaption>Esquema tareas mantenimiento piscinas<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Puesta a punto<\/strong><\/h4>\n\n\n\n<p>En este momento probablemente est\u00e9s pensando, \u00bfpor qu\u00e9 tengo que molestarme en fregar o limpiar cuando a\u00f1ado cloro u otros productos qu\u00edmicos desinfectantes al agua? Es una pregunta v\u00e1lida, y tenemos una respuesta.<\/p>\n\n\n\n<p>Pi\u00e9nsalo de esta manera. Cuando te duchas, usas champ\u00fa y jab\u00f3n, que son agentes de limpieza. \u00bfPero tu ba\u00f1era se mantiene limpia indefinidamente? Por supuesto que no. El champ\u00fa y el jab\u00f3n son para limpiar su cuerpo, no azulejos, baldosas, porcelana o fibra de vidrio. En la&nbsp;<strong>limpieza de piscinas<\/strong>, pasa lo mismo.<\/p>\n\n\n\n<p>Los productos qu\u00edmicos no mantendr\u00e1n las hojas y los insectos fuera del agua, ni mantendr\u00e1n limpias indefinidamente las paredes y el piso. As\u00ed que no hay excusas.<\/p>\n\n\n\n<p>Adem\u00e1s de utilizar cloro u otros productos qu\u00edmicos para mantener la&nbsp;<em>limpieza de la piscina<\/em>, tambi\u00e9n es absolutamente necesaria&nbsp;<em>practicar una desinfecci\u00f3n regular y completa<\/em>&nbsp;de la propia construcci\u00f3n.<\/p>\n\n\n\n<p>En la&nbsp;<strong>puesta a punto de una piscina peque\u00f1a<\/strong>&nbsp;o grande, existen una serie de pasos que deber\u00edamos de verificar y practicar con coherencia:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><em>Limpiar las paredes y el fondo del vaso<\/em><\/li><li><em>Lavar el sistema de filtrado en profundidad y los skimmers<\/em><\/li><li><em>Rellenar la piscina<\/em><\/li><li><em>Regular el valor del pH del agua de la piscina<\/em><\/li><li><em>Aplicar el tratamiento para el agua, sea de cloro o sal<\/em><\/li><li><em>Mantenimiento del agua transparente y sin algas<\/em><\/li><\/ol>\n\n\n\n<p>De una forma m\u00e1s completa con im\u00e1genes vemos&nbsp;<strong>c\u00f3mo limpiar piscinas<\/strong>&nbsp;paso a paso:<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20988\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/consejos-limpieza-piscina-669x1567.jpg\" alt=\"consejos limpieza de piscinas\" class=\"wp-image-20988\"\/><figcaption>V\u00eda Leroy Merlin \u2013 C\u00f3mo limpiar una pileta<\/figcaption><\/figure>\n\n\n\n<p>Ahora, toca las instalaciones\u2026<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Filtraci\u00f3n<\/strong><strong>&nbsp;y circulaci\u00f3n de agua<\/strong><\/h4>\n\n\n\n<p>El&nbsp;<strong>sistema de filtrado en una piscina<\/strong>&nbsp;tampoco es tan complicado pero debemos entender la funci\u00f3n de cada elemento; Skimmers, el sumidero, boquilla de aspiraci\u00f3n, boquillas de impulsi\u00f3n, la bomba, la v\u00e1lvula, el prefiltro y filtro, el cuadro el\u00e9ctrico y el sistema de tuber\u00edas.<\/p>\n\n\n\n<p>El sistema de filtraci\u00f3n son varios dispositivos que se encargan de&nbsp;<em>clarificar el agua<\/em>&nbsp;y filtrarla reteniendo esas part\u00edculas que no queremos que est\u00e9n y devolviendo un agua totalmente limpia. Las caracter\u00edsticas son:<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20996\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/sistema-filtrado-piscina-669x970.jpg\" alt=\"sistema filtrado de piscinas\" class=\"wp-image-20996\"\/><figcaption>V\u00eda Leroy Merlin<\/figcaption><\/figure>\n\n\n\n<p>Hay que tener en cuenta que en el&nbsp;<strong>mantenimiento de piscinas desmontables, prefabricadas o peque\u00f1as<\/strong>, no siempre present\u00e1n un sistema de circulaci\u00f3n tan complejo. Aqu\u00ed juega lo que nos hayamos gastado en la construcci\u00f3n o compra.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo mantener el sistema de filtrado de una piscina?<\/strong><\/h5>\n\n\n\n<p><strong>El lugar y ubicaci\u00f3n de la piscina \u2013 alberca<\/strong>. Tendremos un mayor mantenimiento si est\u00e1 rodeada de \u00e1rboles, c\u00e9sped o arena, que si est\u00e1 rodeada de cemento o madera, o si est\u00e1n protegidas con p\u00e9rgolas o encerradas \u2013 cubiertas autom\u00e1ticas en el jard\u00edn.)<\/p>\n\n\n\n<p><strong>El tiempo que la depuradora estar\u00e1 en marcha<\/strong>. El tiempo adecuado ser\u00eda que al menos pasemos todo el agua dos veces por el filtro durante el d\u00eda. El encendido de una depuradora suele estar entre 4 y 6 horas al d\u00eda, si vemos impurezas y manchas, pues lo subiremos a 7 \u2013 8 Horas.<\/p>\n\n\n\n<p><strong>La bomba puede que sea el elemento m\u00e1s importante de toda la instalaci\u00f3n<\/strong>. La cuant\u00eda de agua que es capaz de aspirar e impulsar se denomina \u00abcaudal\u00bb y que ira en relaci\u00f3n al volumen de la piscina:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/caudal-maximo-bomba.jpg\" alt=\"caudal m\u00e1ximo bomba piscina\" class=\"wp-image-20998\"\/><\/figure><\/div>\n\n\n\n<p>El tama\u00f1o del filtro debe de ir con relaci\u00f3n a la potencia de la bomba de la pila como vemos en la imagen anterior.<\/p>\n\n\n\n<p>En las piscinas modernas encontramos la&nbsp;<strong>v\u00e1lvula o llave de 6 v\u00edas<\/strong>&nbsp;junto al filtro que controla las distintas operaciones de mantenimiento en el circuito;&nbsp;<strong>lavar, enjuague, vaciado,&nbsp; recirculaci\u00f3n o by-pass\u2026etc.&nbsp;<\/strong>Para comprender su funcionamiento dejamos el siguiente esquema:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/operaciones-filtrado-piscin-669x1258.jpg\" alt=\"\" class=\"wp-image-21001\"\/><\/figure><\/div>\n\n\n\n<p><strong>En el mantenimiento del filtro<\/strong>. Hay que tener en cuenta que cuanto m\u00e1s lento sea la velocidad del flujo del agua qu\u00e9 pasa por el filtro mejor ser\u00e1 el filtrado\u2026<strong>\u00bfC\u00f3mo mantener y qu\u00e9 tener en cuenta al usar los filtros?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Filtros de arena<\/strong>: enjuaga el filtro a contralavado cuando la presi\u00f3n aumente de 8 PSI a 10 PSI a partir de la lectura inicial.<\/li><li><strong>Filtros de diatomeas<\/strong>: sigue las instrucciones del filtro para el lavado a contracorriente.<\/li><li><strong>Filtro de cartucho<\/strong>: limpia el filtro siguiendo las instrucciones del filtro.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/como-usar-filtros-piscina-649x373.jpg\" alt=\"como usar los filtros piscina\" class=\"wp-image-20999\"\/><\/figure><\/div>\n\n\n\n<p><strong>En la circulaci\u00f3n del agua<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aseg\u00farate que todos los equipos funcionen correctamente y est\u00e9n colocados en su lugar.<\/li><li>Enciende la bomba y el filtro por lo menos entre 4 y 8 horas por d\u00eda.<\/li><li>Limpia el filtro con qu\u00edmicos al menos dos veces cada estaci\u00f3n.<\/li><li>Limpia las canastas recolectoras y los coladores de pelos y pelusas (en bomba).<\/li><\/ul>\n\n\n\n<p><strong>Los limpiafondos piscina<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Los limpiafondos manuales<\/strong>. Es la opci\u00f3n m\u00e1s barata pero requiere un mayor esfuerzo f\u00edsico y de tiempo. Tambi\u00e9n no sirven para eliminar esas part\u00edculas muy peque\u00f1as que no puede retener el filtro.<\/li><li><strong>Limpiafondos de bater\u00eda e hidr\u00e1ulicos<\/strong>. Estos son capaces de moverse en la pila de forma aut\u00f3noma. No son una buena opci\u00f3n para aquellos vasos con mucha pendiente ya que est\u00e1n dise\u00f1ados para fondos con poca inclinaci\u00f3n y planos.<\/li><li><strong>Limpiadores el\u00e9ctricos<\/strong>. Es la opci\u00f3n m\u00e1s cara y son adecuados para todo tipo de superficies, incluso pueden llegar a subir las paredes del vaso. Son bastante silenciosos y se puede programar, la limpieza es m\u00e1s efectiva.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCada cu\u00e1nto debes realizar el mantenimiento de tu piscina?<\/strong><\/h3>\n\n\n\n<p>El agua est\u00e1 equilibrada cuando en realidad est\u00e1 limpia. El siguiente cuadro indica unos consejos pr\u00e1cticos ante los niveles para un&nbsp;<em>mantenimiento estable de tu piscina<\/em>:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Los par\u00e1metros<\/strong><\/td><td><strong>\u00bfQu\u00e9 es?<\/strong><\/td><td><strong>Cu\u00e1ndo se debe analizar<\/strong><\/td><td><strong>Rango ideal<\/strong><\/td><\/tr><tr><td><strong>pH<\/strong><\/td><td>Una medida de la acidez del agua<\/td><td>2 veces por semana<\/td><td>7,2 \u2013 7,6<\/td><\/tr><tr><td><strong>Cloro residual libre<\/strong><\/td><td>La cantidad de cloro activo en el agua<\/td><td>Todos los d\u00edas<\/td><td>De 0,5 a 2 ppm<\/td><\/tr><tr><td><strong>Alcalinidad total (TA)<\/strong><\/td><td>La capacidad del agua para mantener el pH en un nivel adecuado<\/td><td>Una vez a la semana<\/td><td>De 60 a 120 ppm<\/td><\/tr><tr><td><strong>Dureza del calcio (CH)<\/strong><\/td><td>La cantidad de calcio disuelto en el agua<\/td><td>Una vez a la semana<\/td><td>Aceptable de 200 a 1.000 ppm Ideal: de 200 a 500 ppm<\/td><\/tr><tr><td><strong>Estabilizador de \u00e1cido cian\u00farico (CYA)<\/strong><\/td><td>La medici\u00f3n de la capacidad del cloro de ser protegido de los rayos ultravioletas del sol (estos rayos disminuyen el cloro del agua de la piscina)<\/td><td>Dos veces a la semana<\/td><td>Rango ideal: de 20 a 50 ppm No exceder 100 ppm<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Para esclarecer los valores aceptables en los&nbsp;<strong>par\u00e1metros qu\u00edmicos del agua<\/strong>&nbsp;aportamos la siguiente tabla (Recuerda que estos valores son orientativos y nunca sustituyen a las normas locales, si son de aplicaci\u00f3n)<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20995\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/parametros-quimicos-agua-669x866.jpg\" alt=\"par\u00e1metros qu\u00edmicos agua piscina\" class=\"wp-image-20995\"\/><figcaption>V\u00eda Bluequim<\/figcaption><\/figure>\n\n\n\n<p>IMPORTANTE: Aportamos unos consejos sobre el modo de empleo e instrucciones de aplicaci\u00f3n de los&nbsp;<strong>productos qu\u00edmicos para el tratamiento de piscinas<\/strong>:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/consejos-tratamientos-quimicos-piscinas-669x363.jpg\" alt=\"consejos tratamientos qu\u00edmicos para piscinas\" class=\"wp-image-20984\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Problemas m\u00e1s frecuentes en la piscina y posibles soluciones<\/strong><\/h3>\n\n\n\n<p>En el siguiente esquema veremos los tratamientos de anomal\u00edas m\u00e1s comunes y las posibles correcciones o soluciones. Recuerda que tambi\u00e9n est\u00e1n los profesionales o las tiendas especializadas que nos podr\u00e1n asesorar adecuadamente sobre un problema.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Problema<\/strong><\/td><td><strong>Causa<\/strong><\/td><td><strong>Soluciones<\/strong><\/td><\/tr><tr><td><strong>Cloro combinado elevado<\/strong><\/td><td>Cloraci\u00f3n deficiente. Presencia materia org\u00e1nica y compuestos nitrogenados (Amon\u00edaco)<\/td><td>Ajustar los niveles de cloro. Limpieza de los filtros. Higiene de los ba\u00f1istas. Posible tratamiento de choque Incorporar UV u Ozono<\/td><\/tr><tr><td><strong>Irritaci\u00f3n de los ojos y la piel<\/strong><\/td><td>pH fuera del valor recomendado. Cloro combinado demasiado alto. Presencia materia org\u00e1nica<\/td><td>Ajustar a pH 7.2 \u2013 7.6. Disminuir la cloraminas. Posible tratamiento de choque<\/td><\/tr><tr><td><strong>Agua color verde<\/strong><\/td><td>Presencia de algas<\/td><td>Limpiar y eliminar algas mediante cepillado. Ajustar el pH entre 7.2-7.6. Tratamiento choque. A\u00f1adir floculante y dejar filtrando 24horas. Por \u00faltimo, a\u00f1adir doble cantidad algicida<\/td><\/tr><tr><td><strong>Manchas en las paredes de la piscina<\/strong><\/td><td>Presencia de iones met\u00e1licos debido normalmente a problemas de corrosi\u00f3n<\/td><td>Frotar y limpiar las manchas con un cepillo y un desincrustante de superficies. Ajustar el pH Ajustar la alcalinidad<\/td><\/tr><tr><td><strong>Turbiedad<\/strong><\/td><td>pH y alcalinidad agua alta. Mala filtraci\u00f3n Formaci\u00f3n de algas<\/td><td>Elevar el pH 7,8 Limpiar el filtro. A\u00f1adir floculante y parar el filtro 1 hora. Restablecer valores de pH y alcalinidad. Mantener la filtraci\u00f3n durante 10 horas seguidas<\/td><\/tr><tr><td><strong>Formaci\u00f3n de espumas en el agua<\/strong><\/td><td>Exceso de algicidas. Exceso de materia org\u00e1nica<\/td><td>Tratamiento de choque y posterior ajuste del cloro libre Ajustar el pH Renovar parte del agua de la piscina<\/td><\/tr><tr><td><strong>Incrustaciones en paredes<\/strong><\/td><td>Concentraci\u00f3n elevada de sales de calcio-(Dureza) pH demasiado alto<\/td><td>Realizar una floculaci\u00f3n. Disminuir a pH 7.2. A\u00f1adir productos anticalc\u00e1reos. Disminuir la dureza del agua<\/td><\/tr><tr><td><strong>Agua color marr\u00f3n<\/strong><\/td><td>Presencia de part\u00edculas de hierro o manganeso<\/td><td>Elevar el pH a 7.8. Cloraci\u00f3n de choque. A\u00f1adir floculante. Pasar el limpiafondos<\/td><\/tr><tr><td><strong>Oxidaci\u00f3n partes met\u00e1licas<\/strong><\/td><td>Valores de pH excesivamente bajos. Alcalinidad baja Se produce corrosi\u00f3n partes met\u00e1licas<\/td><td>Ajustar el pH a 7.2 \u2013 7.5. Mantener la Alcalinidad entre 60 \u2013 125 mg\/l<\/td><\/tr><tr><td><strong>Paredes y suelos resbaladizos o verdes<\/strong><\/td><td>Formaci\u00f3n de algas en las paredes y el suelo. Desinfecci\u00f3n incorrecta<\/td><td>Limpiar y eliminar algas mediante cepillado. Ajustar el pH entre 7.2-7.6. Tratamiento choque. A\u00f1adir floculante y dejar filtrando 24horas Por \u00faltimo, a\u00f1adir doble cantidad algicida. Mantener un desinfectante residual correcto<\/td><\/tr><tr><td><strong>Dureza baja<\/strong><\/td><td>Agua de aporte. Aporte de productos qu\u00edmicos. Picaduras en la superficie del vaso. Tendencia a la corrosi\u00f3n<\/td><td>A\u00f1adir cloruro c\u00e1lcico<\/td><\/tr><tr><td><strong>Dureza alta<\/strong><\/td><td>Agua de aporte. Aporte de productos qu\u00edmicos. Incrustaciones Bloqueo de filtros<\/td><td>Sustituci\u00f3n de una parte del agua de la piscina por otra de menor dureza. Tambi\u00e9n se puede conseguir a\u00f1adiendo productos quelantes o secuestrantes que ayuden a mantener disueltas las sales de calcio<\/td><\/tr><tr><td><strong>Alcalinidad baja<\/strong><\/td><td>Agua de aporte. Aporte de productos qu\u00edmicos pH bajo<\/td><td>A\u00f1adir al agua carbonato o bicarbonato s\u00f3dico. (Sustancias alcalinas)<\/td><\/tr><tr><td><strong>Alcalinidad alta<\/strong><\/td><td>Agua de aporte. Aporte de productos qu\u00edmicos pH alto<\/td><td>A\u00f1adir bisulfito s\u00f3dico o \u00e1cido cloh\u00eddrico (sustancias \u00e1cidas)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Recomendaciones mantenimiento piscinas ante COVID19<\/strong><\/h3>\n\n\n\n<p>Con el fin de minimizar el potencial de transmisi\u00f3n de COVID-19 (Coronavirus) y proporcionar un ambiente seguro y saludable en las instalaciones. Hay que entender que se han puesto en marcha diferentes recomendaciones que, aunque est\u00e1n dirigidas para la apertura de piscinas para uso deportivo y piscinas recreativas, es interesante conocerlas para el \u00e1mbito privado.<\/p>\n\n\n\n<p>Aunque seg\u00fan el CSIC (Consejo Superior de Investigaciones Cient\u00edficas) es poco probable el contagio por Covid-19 en el agua tal como rese\u00f1a&nbsp;<a href=\"https:\/\/hidrovinisa.com\/wp-content\/uploads\/2020\/05\/informe_playasypiscinas_csic.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">este documento oficial<\/a>&nbsp;\u00a1Debemos de ser precavidos!<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_26320\"><img decoding=\"async\" src=\"https:\/\/ovacen.com\/wp-content\/uploads\/2018\/08\/recomendaciones-mantenimiento-piscinas-covid-19.jpg\" alt=\"recomendaciones mantenimiento piscinas covid 19 coronavirus\"\/><figcaption>Recomendaciones protecci\u00f3n piscinas contra agentes pat\u00f3genos como el Coronavirus (COVID19)<\/figcaption><\/figure>\n\n\n\n<p>El documento de referencia y recomendaciones&nbsp;<a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/saludAmbLaboral\/calidadAguas\/AGUAYCOVID19\/SARS_COV_2_y_piscinas_14_05_2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">publicado por el Ministerio de Sanidad es este PDF<\/a>&nbsp;(Recomendamos su lectura). Como resumen y conclusiones del informe:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Los riesgos asociados al COVID-19 est\u00e1n relacionados con la interacci\u00f3n entre personas que acuden a las piscinas. Las medidas m\u00e1s eficaces para evitar la transmisi\u00f3n del virus son el distanciamiento social y el refuerzo de la higiene de manos y respiratoria.<\/li><li>La limpieza y desinfecci\u00f3n diaria de superficies y zonas comunes es fundamental \u2013 necesaria para evitar la propagaci\u00f3n del virus.<\/li><li>Para eliminar el virus hay que mantener correctamente el tratamiento y niveles de desinfectante residual en el agua de los vasos y duchas.<\/li><li>Para prevenir la transmisi\u00f3n del virus los usuarios y los trabajadores deben cumplir las medidas de distancia social, cumplir las normas de higiene y aplicar los criterios t\u00e9cnicos de mantenimiento, limpieza y desinfecci\u00f3n.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Consejos para limpiar una piscina y mantenerla todo el a\u00f1o En el verano, casi todos disfrutamos de nuestros ba\u00f1os y chapuzones en alg\u00fan tipo de estanque, sea artificial o no, &hellip; <\/p>\n","protected":false},"author":5,"featured_media":1345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pileta"],"_links":{"self":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=1344"}],"version-history":[{"count":1,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1344\/revisions"}],"predecessor-version":[{"id":1347,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/posts\/1344\/revisions\/1347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media\/1345"}],"wp:attachment":[{"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=1344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=1344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sanitariosplasticos.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=1344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}